{"id":3100,"date":"2020-02-08T09:46:33","date_gmt":"2020-02-08T09:46:33","guid":{"rendered":"http:\/\/www.museosdemequinenza.com\/?p=3100"},"modified":"2020-02-08T09:50:04","modified_gmt":"2020-02-08T09:50:04","slug":"hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza","status":"publish","type":"post","link":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/","title":{"rendered":"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3100\" class=\"elementor elementor-3100 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-daad216 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"daad216\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50ec023\" data-id=\"50ec023\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08af099 elementor-widget elementor-widget-image\" data-id=\"08af099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_42521-scaled-e1581155178875-1024x512.jpg\" class=\"attachment-large size-large wp-image-3101\" alt=\"\" srcset=\"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_42521-scaled-e1581155178875-1024x512.jpg 1024w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_42521-scaled-e1581155178875-300x150.jpg 300w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_42521-scaled-e1581155178875-768x384.jpg 768w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_42521-scaled-e1581155178875-1536x768.jpg 1536w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_42521-scaled-e1581155178875-2048x1024.jpg 2048w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_42521-scaled-e1581155178875-570x285.jpg 570w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_42521-scaled-e1581155178875-380x190.jpg 380w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_42521-scaled-e1581155178875-285x143.jpg 285w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6514341 elementor-widget elementor-widget-text-editor\" data-id=\"6514341\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>\u201cLlega el sombrero loco\u201d ha sido el segundo y \u201cDioses del sol\u201d el tercero. \u201cStempank\u201d y \u201cKurkotransformados\u201d se han llevado los premios a mejor espect\u00e1culo y disfraz m\u00e1s original respectivamente.<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee02d4f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee02d4f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2fe4c3f\" data-id=\"2fe4c3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb1e6be elementor-widget elementor-widget-text-editor\" data-id=\"cb1e6be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El concurso de disfraces en categor\u00eda infantil de las <strong>Festes de Sant Blas i Santa \u00c0gueda de Mequinensa<\/strong>, declarades <strong>Festa d'inter\u00e8s tur\u00edstic d'Arag\u00f3<\/strong>, arrancaba con un total de 22 propuestas inscritas que no han dejado indiferentes al numeroso p\u00fablico que no se ha querido perder el desfile en el Pabell\u00f3n Polideportivo Municipal. Una vez m\u00e1s los dise\u00f1os de estas piezas elaboradas artesanalmente han superado las expectativas lo que se ha traducido en un re\u00f1ido final en el que el Jurado del concurso ha tenido que emplearse a fondo para dar su veredicto.<\/p><p>En juego m\u00e1s de 2.500 euros en premios en met\u00e1lico y suculentos obsequios. El primer premio ha reca\u00eddo en \u201c<strong>Hombre del Saco<\/strong>\u201d, un colorido disfraz con el que se ha querido transmitir el rechazo al bullying, al acoso y a los malos tratos. <strong>Magda Godia<\/strong>, alcaldesa de Mequinenza, ha sido la encargada de entregar el trofeo, los 600 euros en met\u00e1lico del premio, un jam\u00f3n, un vale regalo valorado en 50 \u20ac y una coca de az\u00facar con el que estaba dotado.<\/p><p>El segundo premio se lo ha llevado \u201c<strong>Llega Sombrero Loco<\/strong>\u201d, basado en la pel\u00edcula \u201cAlicia en el Pa\u00eds de las Maravillas\u201d de Tim Burton y dotado con un trofeo, 450 euros en met\u00e1lico, un jam\u00f3n, una tarta y un vale de productos por importe de 40 euros. <strong>Luis Esteve<\/strong>, en sus primeras Fiestas de San Blas y Santa \u00c1gueda como concejal de fiestas, ha entregado el premio. El tercer puesto ha sido para \u201c<strong>Dioses del sol<\/strong>\u201d, de inspiraci\u00f3n Maya, que se ha llevado un trofeo, 400 euros en met\u00e1lico, un jam\u00f3n y vale regalo valorado en 30 euros y de cuya entrega se ha encargado <strong>Coral Beltr\u00e1n<\/strong>, de la Comisi\u00f3n de San Blas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f7446cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7446cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d75a2ba\" data-id=\"d75a2ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bce7ba elementor-widget elementor-widget-image\" data-id=\"2bce7ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3630-1024x683.jpg\" class=\"attachment-large size-large wp-image-3107\" alt=\"\" srcset=\"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3630-1024x683.jpg 1024w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3630-300x200.jpg 300w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3630-768x512.jpg 768w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3630-1536x1024.jpg 1536w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3630-2048x1365.jpg 2048w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3630-1140x760.jpg 1140w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3630-570x380.jpg 570w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3630-380x254.jpg 380w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3630-285x190.jpg 285w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-45efd09\" data-id=\"45efd09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcaf654 elementor-widget elementor-widget-image\" data-id=\"bcaf654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3488-1024x683.jpg\" class=\"attachment-large size-large wp-image-3108\" alt=\"\" srcset=\"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3488-1024x683.jpg 1024w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3488-300x200.jpg 300w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3488-768x512.jpg 768w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3488-1536x1024.jpg 1536w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3488-2048x1365.jpg 2048w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3488-1140x760.jpg 1140w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3488-570x380.jpg 570w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3488-380x254.jpg 380w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_3488-285x190.jpg 285w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a3f6c6 elementor-widget elementor-widget-text-editor\" data-id=\"7a3f6c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\"<strong>La comparsita<\/strong>\u201d, \u201c<strong>Stempank<\/strong>\u201d, \u201c<strong>Pr\u00edncipes del desierto<\/strong>\u201d, \u201c<strong>Los pulpitos<\/strong>\u201d i \u201c<strong>Kurkotransformados<\/strong>\u201d se han llevado los 300, 250, 150, 100 y 75 euros del cuarto al octavo premio que adem\u00e1s esaba acompa\u00f1ado de un jam\u00f3n en cada caso. \u201c<strong>Kurkotransformados<\/strong>\u201d i \u201c<strong>Stempank<\/strong>\u201d se han llevado los premios a disfraz m\u00e1s original y mejor espect\u00e1culo dotados con 100 euros cada uno de ellos.<\/p><p>Ma\u00f1ana por la tarde se celebrar\u00e1 el concurso de disfraces de adultos con otros 2.500 euros en premios en met\u00e1lico en juego y con 24 propuestas inscritas que participar\u00e1n en un pasacalle amenizado por la charanga \u201cla Bancha\u201d antes del desfile en el Pabell\u00f3n Polideportivo Municipal. Por la noche sesi\u00f3n de baile de disfraces en la Sala Vora Riu con la orquesta \u201cTarantella\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u201cLlega el sombrero loco\u201d ha sido el segundo y \u201cDioses del sol\u201d el tercero. \u201cStempank\u201d y \u201cKurkotransformados\u201d se han llevado los premios a mejor espect\u00e1culo y disfraz m\u00e1s original respectivamente. El concurso de disfraces en categor\u00eda infantil de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza, declaradas Fiesta de Inter\u00e9s Tur\u00edstico de Arag\u00f3n,<\/p>\n<p><a href=\"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/\" class=\"more-link themebutton\">Read More<\/a><\/p>","protected":false},"author":1,"featured_media":3101,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u201cLlega el sombrero loco\u201d ha sido el segundo y \u201cDioses del sol\u201d el tercero. \u201cStempank\u201d y \u201cKurkotransformados\u201d se han llevado los premios a mejor espect\u00e1culo y disfraz m\u00e1s original respectivamente. El concurso de disfraces en categor\u00eda infantil de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza, declaradas Fiesta de Inter\u00e9s Tur\u00edstico de Arag\u00f3n,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ca_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"|\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza |\" \/>\n\t\t<meta property=\"og:description\" content=\"\u201cLlega el sombrero loco\u201d ha sido el segundo y \u201cDioses del sol\u201d el tercero. \u201cStempank\u201d y \u201cKurkotransformados\u201d se han llevado los premios a mejor espect\u00e1culo y disfraz m\u00e1s original respectivamente. El concurso de disfraces en categor\u00eda infantil de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza, declaradas Fiesta de Inter\u00e9s Tur\u00edstico de Arag\u00f3n,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-08T09:46:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-02-08T09:50:04+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MuseosdeMequinenza\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@museomequinenza\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza |\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u201cLlega el sombrero loco\u201d ha sido el segundo y \u201cDioses del sol\u201d el tercero. \u201cStempank\u201d y \u201cKurkotransformados\u201d se han llevado los premios a mejor espect\u00e1culo y disfraz m\u00e1s original respectivamente. El concurso de disfraces en categor\u00eda infantil de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza, declaradas Fiesta de Inter\u00e9s Tur\u00edstico de Arag\u00f3n,\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@museomequinenza\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#article\",\"name\":\"\\u201cHombre del Saco\\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \\u00c1gueda de Mequinenza |\",\"headline\":\"\\u201cHombre del Saco\\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \\u00c1gueda de Mequinenza\",\"author\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/author\\\/adminmusmeq\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG_42521-scaled-e1581155178875.jpg\",\"width\":2534,\"height\":1267},\"datePublished\":\"2020-02-08T09:46:33+02:00\",\"dateModified\":\"2020-02-08T09:50:04+02:00\",\"inLanguage\":\"ca\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#webpage\"},\"articleSection\":\"Uncategorized\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Uncategorized\",\"item\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#listItem\",\"name\":\"\\u201cHombre del Saco\\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \\u00c1gueda de Mequinenza\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#listItem\",\"position\":3,\"name\":\"\\u201cHombre del Saco\\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \\u00c1gueda de Mequinenza\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/#organization\",\"name\":\"Museos de Mequinenza\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/\",\"telephone\":\"+34974464705\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.jpg\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#organizationLogo\",\"width\":400,\"height\":400},\"image\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MuseosdeMequinenza\\\/\",\"https:\\\/\\\/twitter.com\\\/museomequinenza\",\"https:\\\/\\\/instagram.com\\\/museosdemequinenza\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@museosdemequinenza\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC1WhAGRfn8YICkw3sNMPvsw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/author\\\/adminmusmeq\\\/#author\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/author\\\/adminmusmeq\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#webpage\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/\",\"name\":\"\\u201cHombre del Saco\\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \\u00c1gueda de Mequinenza |\",\"description\":\"\\u201cLlega el sombrero loco\\u201d ha sido el segundo y \\u201cDioses del sol\\u201d el tercero. \\u201cStempank\\u201d y \\u201cKurkotransformados\\u201d se han llevado los premios a mejor espect\\u00e1culo y disfraz m\\u00e1s original respectivamente. El concurso de disfraces en categor\\u00eda infantil de las Fiestas de San Blas y Santa \\u00c1gueda de Mequinenza, declaradas Fiesta de Inter\\u00e9s Tur\\u00edstico de Arag\\u00f3n,\",\"inLanguage\":\"ca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/author\\\/adminmusmeq\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/author\\\/adminmusmeq\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG_42521-scaled-e1581155178875.jpg\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#mainImage\",\"width\":2534,\"height\":1267},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\\\/#mainImage\"},\"datePublished\":\"2020-02-08T09:46:33+02:00\",\"dateModified\":\"2020-02-08T09:50:04+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/\",\"inLanguage\":\"ca\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza |","description":"\u201cLlega el sombrero loco\u201d ha sido el segundo y \u201cDioses del sol\u201d el tercero. \u201cStempank\u201d y \u201cKurkotransformados\u201d se han llevado los premios a mejor espect\u00e1culo y disfraz m\u00e1s original respectivamente. El concurso de disfraces en categor\u00eda infantil de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza, declaradas Fiesta de Inter\u00e9s Tur\u00edstico de Arag\u00f3n,","canonical_url":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#article","name":"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza |","headline":"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza","author":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/author\/adminmusmeq\/#author"},"publisher":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_42521-scaled-e1581155178875.jpg","width":2534,"height":1267},"datePublished":"2020-02-08T09:46:33+02:00","dateModified":"2020-02-08T09:50:04+02:00","inLanguage":"ca","mainEntityOfPage":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#webpage"},"isPartOf":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#webpage"},"articleSection":"Uncategorized"},{"@type":"BreadcrumbList","@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca#listItem","position":1,"name":"Inicio","item":"https:\/\/www.museosdemequinenza.com\/ca","nextItem":{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/#listItem","name":"Uncategorized"}},{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/#listItem","position":2,"name":"Uncategorized","item":"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#listItem","name":"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#listItem","position":3,"name":"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza","previousItem":{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/#listItem","name":"Uncategorized"}}]},{"@type":"Organization","@id":"https:\/\/www.museosdemequinenza.com\/ca\/#organization","name":"Museos de Mequinenza","url":"https:\/\/www.museosdemequinenza.com\/ca\/","telephone":"+34974464705","logo":{"@type":"ImageObject","url":"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2021\/10\/logo.jpg","@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#organizationLogo","width":400,"height":400},"image":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/MuseosdeMequinenza\/","https:\/\/twitter.com\/museomequinenza","https:\/\/instagram.com\/museosdemequinenza\/","https:\/\/www.tiktok.com\/@museosdemequinenza","https:\/\/www.youtube.com\/channel\/UC1WhAGRfn8YICkw3sNMPvsw"]},{"@type":"Person","@id":"https:\/\/www.museosdemequinenza.com\/ca\/author\/adminmusmeq\/#author","url":"https:\/\/www.museosdemequinenza.com\/ca\/author\/adminmusmeq\/"},{"@type":"WebPage","@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#webpage","url":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/","name":"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza |","description":"\u201cLlega el sombrero loco\u201d ha sido el segundo y \u201cDioses del sol\u201d el tercero. \u201cStempank\u201d y \u201cKurkotransformados\u201d se han llevado los premios a mejor espect\u00e1culo y disfraz m\u00e1s original respectivamente. El concurso de disfraces en categor\u00eda infantil de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza, declaradas Fiesta de Inter\u00e9s Tur\u00edstico de Arag\u00f3n,","inLanguage":"ca","isPartOf":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#breadcrumblist"},"author":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/author\/adminmusmeq\/#author"},"creator":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/author\/adminmusmeq\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2020\/02\/IMG_42521-scaled-e1581155178875.jpg","@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#mainImage","width":2534,"height":1267},"primaryImageOfPage":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/#mainImage"},"datePublished":"2020-02-08T09:46:33+02:00","dateModified":"2020-02-08T09:50:04+02:00"},{"@type":"WebSite","@id":"https:\/\/www.museosdemequinenza.com\/ca\/#website","url":"https:\/\/www.museosdemequinenza.com\/ca\/","inLanguage":"ca","publisher":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/#organization"}}]},"og:locale":"ca_ES","og:site_name":"|","og:type":"article","og:title":"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza |","og:description":"\u201cLlega el sombrero loco\u201d ha sido el segundo y \u201cDioses del sol\u201d el tercero. \u201cStempank\u201d y \u201cKurkotransformados\u201d se han llevado los premios a mejor espect\u00e1culo y disfraz m\u00e1s original respectivamente. El concurso de disfraces en categor\u00eda infantil de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza, declaradas Fiesta de Inter\u00e9s Tur\u00edstico de Arag\u00f3n,","og:url":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/","article:published_time":"2020-02-08T09:46:33+00:00","article:modified_time":"2020-02-08T09:50:04+00:00","article:publisher":"https:\/\/www.facebook.com\/MuseosdeMequinenza\/","twitter:card":"summary","twitter:site":"@museomequinenza","twitter:title":"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza |","twitter:description":"\u201cLlega el sombrero loco\u201d ha sido el segundo y \u201cDioses del sol\u201d el tercero. \u201cStempank\u201d y \u201cKurkotransformados\u201d se han llevado los premios a mejor espect\u00e1culo y disfraz m\u00e1s original respectivamente. El concurso de disfraces en categor\u00eda infantil de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza, declaradas Fiesta de Inter\u00e9s Tur\u00edstico de Arag\u00f3n,","twitter:creator":"@museomequinenza"},"aioseo_meta_data":{"post_id":"3100","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-11 12:27:45","updated":"2025-06-04 10:14:46","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.museosdemequinenza.com\/ca\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/\" title=\"Uncategorized\">Uncategorized<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.museosdemequinenza.com\/ca"},{"label":"Uncategorized","link":"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/"},{"label":"\u201cHombre del Saco\u201d, primer premio del concurso infantil de disfraces de las Fiestas de San Blas y Santa \u00c1gueda de Mequinenza","link":"https:\/\/www.museosdemequinenza.com\/ca\/hombre-del-saco-primer-premio-del-concurso-infantil-de-disfraces-de-las-fiestas-de-san-blas-y-santa-agueda-de-mequinenza\/"}],"_links":{"self":[{"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/posts\/3100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/comments?post=3100"}],"version-history":[{"count":3,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/posts\/3100\/revisions"}],"predecessor-version":[{"id":3109,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/posts\/3100\/revisions\/3109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/media\/3101"}],"wp:attachment":[{"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/media?parent=3100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/categories?post=3100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/tags?post=3100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}