{"id":2319,"date":"2019-09-04T08:36:50","date_gmt":"2019-09-04T08:36:50","guid":{"rendered":"http:\/\/www.museosdemequinenza.com\/?p=2319"},"modified":"2019-09-04T08:38:44","modified_gmt":"2019-09-04T08:38:44","slug":"mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou","status":"publish","type":"post","link":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/","title":{"rendered":"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2319\" class=\"elementor elementor-2319 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-152da2f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"152da2f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6aad365\" data-id=\"6aad365\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfd48aa elementor-widget elementor-widget-image\" data-id=\"dfd48aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1140\" height=\"380\" src=\"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2019\/09\/poble-vell-i-nou-e1567586197811-1140x380.jpg\" class=\"attachment-column1-1\/3 size-column1-1\/3 wp-image-2320\" alt=\"\" srcset=\"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2019\/09\/poble-vell-i-nou-e1567586197811-1140x380.jpg 1140w, https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2019\/09\/poble-vell-i-nou-e1567586197811-380x127.jpg 380w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9962a6 elementor-widget elementor-widget-text-editor\" data-id=\"a9962a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Las actividades se prolongar\u00e1n durante un a\u00f1o y arrancar\u00e1n a finales de primavera recordando una de las etapas m\u00e1s importantes en la historia reciente de la localidad: el traslado del \u201cPoble Vell\u201d.<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a2dc21 elementor-widget elementor-widget-text-editor\" data-id=\"1a2dc21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bajo el t\u00edtulo gen\u00e9rico de <strong>\u201cMequinenza 1970-2020. 50 a\u00f1os de \u2018Poble Nou'\u00bb<\/strong>, a partir de finales de la primavera del pr\u00f3ximo a\u00f1o la localidad conmemorar\u00e1 el 50 aniversario del traslado del \u201cPoble Vell\u201d, el antiguo n\u00facleo urbano a orillas del r\u00edo Ebro, al actual, junto al Segre. Una de las etapas m\u00e1s importantes en la historia reciente del municipio motivado por la construcci\u00f3n del embalse de Riba-roja.<\/p><p>Las fechas de la celebraci\u00f3n se hacen coincidir con la llegada del grueso de los vecinos a sus nuevas viviendas en el \u201cPoble Nou\u201d. En cuanto al programa de actos, que se encuentra en fase embrionaria y que se har\u00e1 p\u00fablico tal y como se aproxime la conmemoraci\u00f3n, est\u00e1 previsto que incluya, entre otras, exposiciones, charlas y publicaciones.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Las actividades se prolongar\u00e1n durante un a\u00f1o y arrancar\u00e1n a finales de primavera recordando una de las etapas m\u00e1s importantes en la historia reciente de la localidad: el traslado del \u201cPoble Vell\u201d. Bajo el t\u00edtulo gen\u00e9rico de \u201cMequinenza 1970-2020. 50 a\u00f1os de \u2018Poble Nou&#8217;\u00bb, a partir de finales de la primavera del pr\u00f3ximo a\u00f1o la<\/p>\n<p><a href=\"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/\" class=\"more-link themebutton\">Read More<\/a><\/p>","protected":false},"author":1,"featured_media":2320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las actividades se prolongar\u00e1n durante un a\u00f1o y arrancar\u00e1n a finales de primavera recordando una de las etapas m\u00e1s importantes en la historia reciente de la localidad: el traslado del \u201cPoble Vell\u201d. Bajo el t\u00edtulo gen\u00e9rico de \u201cMequinenza 1970-2020. 50 a\u00f1os de \u2018Poble Nou&#039;\u00bb, a partir de finales de la primavera del pr\u00f3ximo a\u00f1o la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ca_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"|\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d |\" \/>\n\t\t<meta property=\"og:description\" content=\"Las actividades se prolongar\u00e1n durante un a\u00f1o y arrancar\u00e1n a finales de primavera recordando una de las etapas m\u00e1s importantes en la historia reciente de la localidad: el traslado del \u201cPoble Vell\u201d. Bajo el t\u00edtulo gen\u00e9rico de \u201cMequinenza 1970-2020. 50 a\u00f1os de \u2018Poble Nou&#039;\u00bb, a partir de finales de la primavera del pr\u00f3ximo a\u00f1o la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-09-04T08:36:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-09-04T08:38:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MuseosdeMequinenza\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@museomequinenza\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d |\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las actividades se prolongar\u00e1n durante un a\u00f1o y arrancar\u00e1n a finales de primavera recordando una de las etapas m\u00e1s importantes en la historia reciente de la localidad: el traslado del \u201cPoble Vell\u201d. Bajo el t\u00edtulo gen\u00e9rico de \u201cMequinenza 1970-2020. 50 a\u00f1os de \u2018Poble Nou&#039;\u00bb, a partir de finales de la primavera del pr\u00f3ximo a\u00f1o la\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@museomequinenza\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#article\",\"name\":\"Mequinenza se prepara para conmemorar 50 a\\u00f1os de \\u201cPoble Nou\\u201d |\",\"headline\":\"Mequinenza se prepara para conmemorar 50 a\\u00f1os de \\u201cPoble Nou\\u201d\",\"author\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/author\\\/adminmusmeq\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/poble-vell-i-nou-e1567586197811.jpg\",\"width\":1467,\"height\":733,\"caption\":\"Mequinenza 1970-2020. 50 a\\u00f1os de 'Poble Nou\"},\"datePublished\":\"2019-09-04T08:36:50+02:00\",\"dateModified\":\"2019-09-04T08:38:44+02:00\",\"inLanguage\":\"ca\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#webpage\"},\"articleSection\":\"Uncategorized\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Uncategorized\",\"item\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#listItem\",\"name\":\"Mequinenza se prepara para conmemorar 50 a\\u00f1os de \\u201cPoble Nou\\u201d\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#listItem\",\"position\":3,\"name\":\"Mequinenza se prepara para conmemorar 50 a\\u00f1os de \\u201cPoble Nou\\u201d\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/#organization\",\"name\":\"Museos de Mequinenza\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/\",\"telephone\":\"+34974464705\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo.jpg\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#organizationLogo\",\"width\":400,\"height\":400},\"image\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MuseosdeMequinenza\\\/\",\"https:\\\/\\\/twitter.com\\\/museomequinenza\",\"https:\\\/\\\/instagram.com\\\/museosdemequinenza\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@museosdemequinenza\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC1WhAGRfn8YICkw3sNMPvsw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/author\\\/adminmusmeq\\\/#author\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/author\\\/adminmusmeq\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#webpage\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/\",\"name\":\"Mequinenza se prepara para conmemorar 50 a\\u00f1os de \\u201cPoble Nou\\u201d |\",\"description\":\"Las actividades se prolongar\\u00e1n durante un a\\u00f1o y arrancar\\u00e1n a finales de primavera recordando una de las etapas m\\u00e1s importantes en la historia reciente de la localidad: el traslado del \\u201cPoble Vell\\u201d. Bajo el t\\u00edtulo gen\\u00e9rico de \\u201cMequinenza 1970-2020. 50 a\\u00f1os de \\u2018Poble Nou'\\u00bb, a partir de finales de la primavera del pr\\u00f3ximo a\\u00f1o la\",\"inLanguage\":\"ca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/author\\\/adminmusmeq\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/author\\\/adminmusmeq\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/poble-vell-i-nou-e1567586197811.jpg\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#mainImage\",\"width\":1467,\"height\":733,\"caption\":\"Mequinenza 1970-2020. 50 a\\u00f1os de 'Poble Nou\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\\\/#mainImage\"},\"datePublished\":\"2019-09-04T08:36:50+02:00\",\"dateModified\":\"2019-09-04T08:38:44+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/\",\"inLanguage\":\"ca\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.museosdemequinenza.com\\\/ca\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d |","description":"Las actividades se prolongar\u00e1n durante un a\u00f1o y arrancar\u00e1n a finales de primavera recordando una de las etapas m\u00e1s importantes en la historia reciente de la localidad: el traslado del \u201cPoble Vell\u201d. Bajo el t\u00edtulo gen\u00e9rico de \u201cMequinenza 1970-2020. 50 a\u00f1os de \u2018Poble Nou'\u00bb, a partir de finales de la primavera del pr\u00f3ximo a\u00f1o la","canonical_url":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#article","name":"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d |","headline":"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d","author":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/author\/adminmusmeq\/#author"},"publisher":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2019\/09\/poble-vell-i-nou-e1567586197811.jpg","width":1467,"height":733,"caption":"Mequinenza 1970-2020. 50 a\u00f1os de 'Poble Nou"},"datePublished":"2019-09-04T08:36:50+02:00","dateModified":"2019-09-04T08:38:44+02:00","inLanguage":"ca","mainEntityOfPage":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#webpage"},"isPartOf":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#webpage"},"articleSection":"Uncategorized"},{"@type":"BreadcrumbList","@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca#listItem","position":1,"name":"Inicio","item":"https:\/\/www.museosdemequinenza.com\/ca","nextItem":{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/#listItem","name":"Uncategorized"}},{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/#listItem","position":2,"name":"Uncategorized","item":"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#listItem","name":"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#listItem","position":3,"name":"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d","previousItem":{"@type":"ListItem","@id":"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/#listItem","name":"Uncategorized"}}]},{"@type":"Organization","@id":"https:\/\/www.museosdemequinenza.com\/ca\/#organization","name":"Museos de Mequinenza","url":"https:\/\/www.museosdemequinenza.com\/ca\/","telephone":"+34974464705","logo":{"@type":"ImageObject","url":"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2021\/10\/logo.jpg","@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#organizationLogo","width":400,"height":400},"image":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/MuseosdeMequinenza\/","https:\/\/twitter.com\/museomequinenza","https:\/\/instagram.com\/museosdemequinenza\/","https:\/\/www.tiktok.com\/@museosdemequinenza","https:\/\/www.youtube.com\/channel\/UC1WhAGRfn8YICkw3sNMPvsw"]},{"@type":"Person","@id":"https:\/\/www.museosdemequinenza.com\/ca\/author\/adminmusmeq\/#author","url":"https:\/\/www.museosdemequinenza.com\/ca\/author\/adminmusmeq\/"},{"@type":"WebPage","@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#webpage","url":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/","name":"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d |","description":"Las actividades se prolongar\u00e1n durante un a\u00f1o y arrancar\u00e1n a finales de primavera recordando una de las etapas m\u00e1s importantes en la historia reciente de la localidad: el traslado del \u201cPoble Vell\u201d. Bajo el t\u00edtulo gen\u00e9rico de \u201cMequinenza 1970-2020. 50 a\u00f1os de \u2018Poble Nou'\u00bb, a partir de finales de la primavera del pr\u00f3ximo a\u00f1o la","inLanguage":"ca","isPartOf":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#breadcrumblist"},"author":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/author\/adminmusmeq\/#author"},"creator":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/author\/adminmusmeq\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.museosdemequinenza.com\/wp-content\/uploads\/2019\/09\/poble-vell-i-nou-e1567586197811.jpg","@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#mainImage","width":1467,"height":733,"caption":"Mequinenza 1970-2020. 50 a\u00f1os de 'Poble Nou"},"primaryImageOfPage":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/#mainImage"},"datePublished":"2019-09-04T08:36:50+02:00","dateModified":"2019-09-04T08:38:44+02:00"},{"@type":"WebSite","@id":"https:\/\/www.museosdemequinenza.com\/ca\/#website","url":"https:\/\/www.museosdemequinenza.com\/ca\/","inLanguage":"ca","publisher":{"@id":"https:\/\/www.museosdemequinenza.com\/ca\/#organization"}}]},"og:locale":"ca_ES","og:site_name":"|","og:type":"article","og:title":"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d |","og:description":"Las actividades se prolongar\u00e1n durante un a\u00f1o y arrancar\u00e1n a finales de primavera recordando una de las etapas m\u00e1s importantes en la historia reciente de la localidad: el traslado del \u201cPoble Vell\u201d. Bajo el t\u00edtulo gen\u00e9rico de \u201cMequinenza 1970-2020. 50 a\u00f1os de \u2018Poble Nou'\u00bb, a partir de finales de la primavera del pr\u00f3ximo a\u00f1o la","og:url":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/","article:published_time":"2019-09-04T08:36:50+00:00","article:modified_time":"2019-09-04T08:38:44+00:00","article:publisher":"https:\/\/www.facebook.com\/MuseosdeMequinenza\/","twitter:card":"summary","twitter:site":"@museomequinenza","twitter:title":"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d |","twitter:description":"Las actividades se prolongar\u00e1n durante un a\u00f1o y arrancar\u00e1n a finales de primavera recordando una de las etapas m\u00e1s importantes en la historia reciente de la localidad: el traslado del \u201cPoble Vell\u201d. Bajo el t\u00edtulo gen\u00e9rico de \u201cMequinenza 1970-2020. 50 a\u00f1os de \u2018Poble Nou'\u00bb, a partir de finales de la primavera del pr\u00f3ximo a\u00f1o la","twitter:creator":"@museomequinenza"},"aioseo_meta_data":{"post_id":"2319","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-11 12:27:43","updated":"2025-06-04 10:04:45","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.museosdemequinenza.com\/ca\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/\" title=\"Uncategorized\">Uncategorized<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.museosdemequinenza.com\/ca"},{"label":"Uncategorized","link":"https:\/\/www.museosdemequinenza.com\/ca\/category\/uncategorized\/"},{"label":"Mequinenza se prepara para conmemorar 50 a\u00f1os de \u201cPoble Nou\u201d","link":"https:\/\/www.museosdemequinenza.com\/ca\/mequinenza-se-prepara-para-conmemorar-50-anos-de-poble-nou\/"}],"_links":{"self":[{"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/posts\/2319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/comments?post=2319"}],"version-history":[{"count":2,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/posts\/2319\/revisions"}],"predecessor-version":[{"id":2325,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/posts\/2319\/revisions\/2325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/media\/2320"}],"wp:attachment":[{"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/media?parent=2319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/categories?post=2319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.museosdemequinenza.com\/ca\/wp-json\/wp\/v2\/tags?post=2319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}